{"id":14201,"date":"2026-03-07T18:25:18","date_gmt":"2026-03-07T18:25:18","guid":{"rendered":"https:\/\/languagetreeschool.com\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/"},"modified":"2026-03-07T18:25:18","modified_gmt":"2026-03-07T18:25:18","slug":"parco-avventura-kernow","status":"publish","type":"page","link":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/","title":{"rendered":"Parco Avventura Kernow"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":6500,"parent":4627,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-14201","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva<\/title>\n<meta name=\"description\" content=\"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva\" \/>\n<meta property=\"og:description\" content=\"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/\" \/>\n<meta property=\"og:site_name\" content=\"Language Tree\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/languagetreecornwall\" \/>\n<meta property=\"og:image\" content=\"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva\" \/>\n<meta name=\"twitter:description\" content=\"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/\",\"name\":\"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"datePublished\":\"2026-03-07T18:25:18+00:00\",\"description\":\"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"width\":2000,\"height\":1334,\"caption\":\"SUP giganti e gonfiabili al Parco Avventura Kernow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/parco-avventura-kernow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/pagina-iniziale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra scuola\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Attivit\u00e0 sociali ed escursioni\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/la-nostra-scuola\\\/attivita-sociali-ed-escursioni\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Parco Avventura Kernow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/\",\"name\":\"Language Tree\",\"description\":\"Language, culture &amp; adventure\",\"publisher\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#organization\",\"name\":\"Language Tree\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"width\":1396,\"height\":1909,\"caption\":\"Language Tree\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/languagetreecornwall\",\"https:\\\/\\\/www.instagram.com\\\/languagetreeschool\"],\"description\":\"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.\",\"email\":\"info@languagetreeschool.com\",\"telephone\":\"+447957497937\",\"legalName\":\"Language Tree Limited\",\"foundingDate\":\"2011-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva","description":"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/","og_locale":"it_IT","og_type":"article","og_title":"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva","og_description":"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.","og_url":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/","og_site_name":"Language Tree","article_publisher":"https:\/\/www.facebook.com\/languagetreecornwall","og_image":[{"width":2000,"height":1334,"url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva","twitter_description":"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/","url":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/","name":"Un divertente parco acquatico per gli adolescenti durante la nostra scuola estiva","isPartOf":{"@id":"https:\/\/languagetreeschool.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/#primaryimage"},"image":{"@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/#primaryimage"},"thumbnailUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","datePublished":"2026-03-07T18:25:18+00:00","description":"I pomeriggi al Kernow Adventure Park sono sempre molto divertenti! Gli studenti junior adorano i gonfiabili in stile Total Wipeout e le tavole da paddle giganti.","breadcrumb":{"@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/#primaryimage","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","width":2000,"height":1334,"caption":"SUP giganti e gonfiabili al Parco Avventura Kernow"},{"@type":"BreadcrumbList","@id":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/parco-avventura-kernow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/languagetreeschool.com\/it\/pagina-iniziale\/"},{"@type":"ListItem","position":2,"name":"La nostra scuola","item":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/"},{"@type":"ListItem","position":3,"name":"Attivit\u00e0 sociali ed escursioni","item":"https:\/\/languagetreeschool.com\/it\/la-nostra-scuola\/attivita-sociali-ed-escursioni\/"},{"@type":"ListItem","position":4,"name":"Parco Avventura Kernow"}]},{"@type":"WebSite","@id":"https:\/\/languagetreeschool.com\/it\/#website","url":"https:\/\/languagetreeschool.com\/it\/","name":"Language Tree","description":"Language, culture &amp; adventure","publisher":{"@id":"https:\/\/languagetreeschool.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/languagetreeschool.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/languagetreeschool.com\/it\/#organization","name":"Language Tree","url":"https:\/\/languagetreeschool.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/languagetreeschool.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","width":1396,"height":1909,"caption":"Language Tree"},"image":{"@id":"https:\/\/languagetreeschool.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/languagetreecornwall","https:\/\/www.instagram.com\/languagetreeschool"],"description":"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.","email":"info@languagetreeschool.com","telephone":"+447957497937","legalName":"Language Tree Limited","foundingDate":"2011-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/pages\/14201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/comments?post=14201"}],"version-history":[{"count":0,"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/pages\/14201\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/pages\/4627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/media\/6500"}],"wp:attachment":[{"href":"https:\/\/languagetreeschool.com\/it\/wp-json\/wp\/v2\/media?parent=14201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}