{"id":14203,"date":"2026-03-07T18:25:18","date_gmt":"2026-03-07T18:25:18","guid":{"rendered":"https:\/\/languagetreeschool.com\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/"},"modified":"2026-03-07T18:25:18","modified_gmt":"2026-03-07T18:25:18","slug":"parque-de-aventuras-kernow","status":"publish","type":"page","link":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/","title":{"rendered":"Parque de Aventuras Kernow"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":6504,"parent":4631,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-14203","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano<\/title>\n<meta name=\"description\" content=\"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano\" \/>\n<meta property=\"og:description\" content=\"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/\" \/>\n<meta property=\"og:site_name\" content=\"Language Tree\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/languagetreecornwall\" \/>\n<meta property=\"og:image\" content=\"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano\" \/>\n<meta name=\"twitter:description\" content=\"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/\",\"name\":\"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"datePublished\":\"2026-03-07T18:25:18+00:00\",\"description\":\"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/giant-SUP.jpg\",\"width\":2000,\"height\":1334,\"caption\":\"SUP gigante e hinchables en el Parque de Aventuras Kernow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/parque-de-aventuras-kernow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/pagina-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestra escuela\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actividades sociales y excursiones\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/nuestra-escuela\\\/actividades-sociales-y-excursiones\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Parque de Aventuras Kernow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/\",\"name\":\"Language Tree\",\"description\":\"Language, culture &amp; adventure\",\"publisher\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#organization\",\"name\":\"Language Tree\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"width\":1396,\"height\":1909,\"caption\":\"Language Tree\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/languagetreecornwall\",\"https:\\\/\\\/www.instagram.com\\\/languagetreeschool\"],\"description\":\"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.\",\"email\":\"info@languagetreeschool.com\",\"telephone\":\"+447957497937\",\"legalName\":\"Language Tree Limited\",\"foundingDate\":\"2011-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano","description":"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/","og_locale":"es_ES","og_type":"article","og_title":"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano","og_description":"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.","og_url":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/","og_site_name":"Language Tree","article_publisher":"https:\/\/www.facebook.com\/languagetreecornwall","og_image":[{"width":2000,"height":1334,"url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano","twitter_description":"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/","url":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/","name":"Divertido parque acu\u00e1tico para que los adolescentes disfruten en nuestra escuela de verano","isPartOf":{"@id":"https:\/\/languagetreeschool.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/#primaryimage"},"image":{"@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/#primaryimage"},"thumbnailUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","datePublished":"2026-03-07T18:25:18+00:00","description":"\u00a1Las tardes en el Parque de Aventuras Kernow son siempre muy divertidas! A los alumnos junior les encantan sus hinchables estilo Total Wipeout y las tablas de paddle gigantes.","breadcrumb":{"@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/#primaryimage","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/08\/giant-SUP.jpg","width":2000,"height":1334,"caption":"SUP gigante e hinchables en el Parque de Aventuras Kernow"},{"@type":"BreadcrumbList","@id":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/parque-de-aventuras-kernow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/languagetreeschool.com\/es\/pagina-inicio\/"},{"@type":"ListItem","position":2,"name":"Nuestra escuela","item":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/"},{"@type":"ListItem","position":3,"name":"Actividades sociales y excursiones","item":"https:\/\/languagetreeschool.com\/es\/nuestra-escuela\/actividades-sociales-y-excursiones\/"},{"@type":"ListItem","position":4,"name":"Parque de Aventuras Kernow"}]},{"@type":"WebSite","@id":"https:\/\/languagetreeschool.com\/es\/#website","url":"https:\/\/languagetreeschool.com\/es\/","name":"Language Tree","description":"Language, culture &amp; adventure","publisher":{"@id":"https:\/\/languagetreeschool.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/languagetreeschool.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/languagetreeschool.com\/es\/#organization","name":"Language Tree","url":"https:\/\/languagetreeschool.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/languagetreeschool.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","width":1396,"height":1909,"caption":"Language Tree"},"image":{"@id":"https:\/\/languagetreeschool.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/languagetreecornwall","https:\/\/www.instagram.com\/languagetreeschool"],"description":"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.","email":"info@languagetreeschool.com","telephone":"+447957497937","legalName":"Language Tree Limited","foundingDate":"2011-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/pages\/14203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/comments?post=14203"}],"version-history":[{"count":0,"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/pages\/14203\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/pages\/4631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/media\/6504"}],"wp:attachment":[{"href":"https:\/\/languagetreeschool.com\/es\/wp-json\/wp\/v2\/media?parent=14203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}