{"id":13037,"date":"2025-12-06T11:17:25","date_gmt":"2025-12-06T11:17:25","guid":{"rendered":"https:\/\/languagetreeschool.com\/?p=13037"},"modified":"2025-12-12T07:51:18","modified_gmt":"2025-12-12T07:51:18","slug":"film-und-fernsehserien-mit-sitz-in-cornwall","status":"publish","type":"post","link":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/","title":{"rendered":"Film- und Fernsehserien mit Sitz in Cornwall"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":3581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1191,1023,1238,1148,1147,1237,921,1078,1032],"tags":[],"class_list":["post-13037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cornwall-stadte","category-exkursionen","category-film-fernsehen","category-geschichte","category-kornisches-erbe","category-kunst-kultur","category-neueste-nachrichten","category-orte-in-cornwall","category-strande-von-cornwall-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall<\/title>\n<meta name=\"description\" content=\"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall\" \/>\n<meta property=\"og:description\" content=\"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/\" \/>\n<meta property=\"og:site_name\" content=\"Language Tree\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/languagetreecornwall\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-06T11:17:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T07:51:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katy Daly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall\" \/>\n<meta name=\"twitter:description\" content=\"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katy Daly\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/\"},\"author\":{\"name\":\"Katy Daly\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#\\\/schema\\\/person\\\/c477eb0fe4f3c81bc317ae30fa731b44\"},\"headline\":\"Film- und Fernsehserien mit Sitz in Cornwall\",\"datePublished\":\"2025-12-06T11:17:25+00:00\",\"dateModified\":\"2025-12-12T07:51:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WLT-poldark.jpg\",\"articleSection\":[\"Cornwall-St\u00e4dte\",\"Exkursionen\",\"Film &amp; Fernsehen\",\"Geschichte\",\"Kornisches Erbe\",\"Kunst &amp; Kultur\",\"Neueste Nachrichten\",\"Orte in Cornwall\",\"Str\u00e4nde von Cornwall\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/\",\"name\":\"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WLT-poldark.jpg\",\"datePublished\":\"2025-12-06T11:17:25+00:00\",\"dateModified\":\"2025-12-12T07:51:18+00:00\",\"description\":\"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WLT-poldark.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WLT-poldark.jpg\",\"width\":1025,\"height\":769,\"caption\":\"Ein Filmteam am Strand von Porthgwarra bei den Dreharbeiten zu Poldark.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/orte-in-cornwall\\\/film-fernsehen\\\/film-und-fernsehserien-mit-sitz-in-cornwall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Film- und Fernsehserien mit Sitz in Cornwall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/\",\"name\":\"Language Tree\",\"description\":\"Language, culture &amp; adventure\",\"publisher\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#organization\",\"name\":\"Language Tree\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/LT-icon-1.jpg\",\"width\":1396,\"height\":1909,\"caption\":\"Language Tree\"},\"image\":{\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/languagetreecornwall\",\"https:\\\/\\\/www.instagram.com\\\/languagetreeschool\"],\"description\":\"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.\",\"email\":\"info@languagetreeschool.com\",\"telephone\":\"+447957497937\",\"legalName\":\"Language Tree Limited\",\"foundingDate\":\"2011-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/#\\\/schema\\\/person\\\/c477eb0fe4f3c81bc317ae30fa731b44\",\"name\":\"Katy Daly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095\",\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095\",\"contentUrl\":\"https:\\\/\\\/languagetreeschool.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095\",\"caption\":\"Katy Daly\"},\"url\":\"https:\\\/\\\/languagetreeschool.com\\\/de\\\/author\\\/katy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall","description":"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/","og_locale":"de_DE","og_type":"article","og_title":"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall","og_description":"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen","og_url":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/","og_site_name":"Language Tree","article_publisher":"https:\/\/www.facebook.com\/languagetreecornwall","article_published_time":"2025-12-06T11:17:25+00:00","article_modified_time":"2025-12-12T07:51:18+00:00","og_image":[{"width":1025,"height":769,"url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg","type":"image\/jpeg"}],"author":"Katy Daly","twitter_card":"summary_large_image","twitter_title":"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall","twitter_description":"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen","twitter_misc":{"Verfasst von":"Katy Daly"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#article","isPartOf":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/"},"author":{"name":"Katy Daly","@id":"https:\/\/languagetreeschool.com\/de\/#\/schema\/person\/c477eb0fe4f3c81bc317ae30fa731b44"},"headline":"Film- und Fernsehserien mit Sitz in Cornwall","datePublished":"2025-12-06T11:17:25+00:00","dateModified":"2025-12-12T07:51:18+00:00","mainEntityOfPage":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/languagetreeschool.com\/de\/#organization"},"image":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#primaryimage"},"thumbnailUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg","articleSection":["Cornwall-St\u00e4dte","Exkursionen","Film &amp; Fernsehen","Geschichte","Kornisches Erbe","Kunst &amp; Kultur","Neueste Nachrichten","Orte in Cornwall","Str\u00e4nde von Cornwall"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/","url":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/","name":"Besuchen Sie mit Language Tree wundersch\u00f6ne Film- und TV-Drehorte in Cornwall","isPartOf":{"@id":"https:\/\/languagetreeschool.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#primaryimage"},"image":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#primaryimage"},"thumbnailUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg","datePublished":"2025-12-06T11:17:25+00:00","dateModified":"2025-12-12T07:51:18+00:00","description":"Besuchen Sie ber\u00fchmte Film- und TV-Drehorte in Cornwall und genie\u00dfen Sie die wundersch\u00f6ne Kulisse Ihrer Lieblingsfilme bei unseren Spracherlebnissen","breadcrumb":{"@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#primaryimage","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2025\/07\/WLT-poldark.jpg","width":1025,"height":769,"caption":"Ein Filmteam am Strand von Porthgwarra bei den Dreharbeiten zu Poldark."},{"@type":"BreadcrumbList","@id":"https:\/\/languagetreeschool.com\/de\/orte-in-cornwall\/film-fernsehen\/film-und-fernsehserien-mit-sitz-in-cornwall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/languagetreeschool.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Film- und Fernsehserien mit Sitz in Cornwall"}]},{"@type":"WebSite","@id":"https:\/\/languagetreeschool.com\/de\/#website","url":"https:\/\/languagetreeschool.com\/de\/","name":"Language Tree","description":"Language, culture &amp; adventure","publisher":{"@id":"https:\/\/languagetreeschool.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/languagetreeschool.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/languagetreeschool.com\/de\/#organization","name":"Language Tree","url":"https:\/\/languagetreeschool.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/languagetreeschool.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/uploads\/2026\/03\/LT-icon-1.jpg","width":1396,"height":1909,"caption":"Language Tree"},"image":{"@id":"https:\/\/languagetreeschool.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/languagetreecornwall","https:\/\/www.instagram.com\/languagetreeschool"],"description":"British Council accredited English language Summer School in Cornwall. Welcoming teenagers, families and adults from around the world to our university campus.","email":"info@languagetreeschool.com","telephone":"+447957497937","legalName":"Language Tree Limited","foundingDate":"2011-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/languagetreeschool.com\/de\/#\/schema\/person\/c477eb0fe4f3c81bc317ae30fa731b44","name":"Katy Daly","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/languagetreeschool.com\/wp-content\/litespeed\/avatar\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095","url":"https:\/\/languagetreeschool.com\/wp-content\/litespeed\/avatar\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095","contentUrl":"https:\/\/languagetreeschool.com\/wp-content\/litespeed\/avatar\/ce98e82e4236450838bda49e07610cf8.jpg?ver=1778323095","caption":"Katy Daly"},"url":"https:\/\/languagetreeschool.com\/de\/author\/katy\/"}]}},"_links":{"self":[{"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/posts\/13037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/comments?post=13037"}],"version-history":[{"count":2,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/posts\/13037\/revisions"}],"predecessor-version":[{"id":13401,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/posts\/13037\/revisions\/13401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/media\/3581"}],"wp:attachment":[{"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/media?parent=13037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/categories?post=13037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/languagetreeschool.com\/de\/wp-json\/wp\/v2\/tags?post=13037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}